{"id":3452,"date":"2025-02-17T23:02:12","date_gmt":"2025-02-17T22:02:12","guid":{"rendered":"https:\/\/miha.nl\/mio\/?post_type=product&#038;p=3452"},"modified":"2025-03-08T13:18:31","modified_gmt":"2025-03-08T12:18:31","slug":"mio-mivue-c545pro-dashcam-full-hdhdr2m-sensor","status":"publish","type":"product","link":"https:\/\/miha.nl\/mio\/product\/mio-mivue-c545pro-dashcam-full-hdhdr2m-sensor\/","title":{"rendered":"Mio MiVue C545PRO dashcam Full HD+HDR+2M sensor"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3453\" src=\"https:\/\/miha.nl\/mio\/wp-content\/uploads\/2025\/02\/MioMivueC545Pro-300x300.jpg\" alt=\"Mio MiVue C545 Pro\" width=\"300\" height=\"300\" \/><\/p>\n<h1>Mio MiVue C545PRO dashcam Full HD+HDR+2M sensor<\/h1>\n<p>Met Sony STARVIS CMOS-sensor.(dit maakt hem de C545 Pro)<\/p>\n<p>Maak kennis met de MiVue C545 Pro, de ultieme dashcam voor superieure videokwaliteit. Ontworpen met alleen topklasse videotechnologie legt de MiVue C545 Pro elk moment op de weg vast in briljant detail, dag en nacht.<\/p>\n<p>Met Full HD 1080p opname bij 60 fps en Sony&#8217;s eersteklas STARVIS CMOS-sensor blinkt de MiVue C545 Pro uit in het vastleggen van scherpe, heldere beelden, vooral bij weinig licht. Of u nu onder de middagzon of door slecht verlichte straten rijdt, de MiVue C545 Pro garandeert gedetailleerde beelden met levendige kleuren en een uitzonderlijk contrast.<\/p>\n<p>Wanneer fel licht of de schittering van koplampen belangrijke details zoals nummerborden kan verbergen, grijpt HDR in door automatisch meerdere frames te balanceren en te verbeteren, waardoor scherpere beelden worden geproduceerd. Met HDR krijg je kristalheldere beelden, zodat je het duidelijke bewijs hebt dat je nodig hebt als het er echt toe doet.<\/p>\n<p>Het grote diafragma van F1.8 en de kijkhoek van 140 graden bieden een extra breed beeld van je omgeving, zodat niets aan het zicht van je dashcam ontsnapt. De toegevoegde Mio Night Vision Technologie verbetert de videokwaliteit nog verder, dankzij professionele beeldafstemming en een hoogwaardige glazen lens die is ontworpen voor superieure lichttransmissie.<\/p>\n<p>De ingebouwde G-sensor vergrendelt beelden tijdens plotselinge bewegingen of botsingen, zodat je belangrijke bestanden niet worden overschreven. En met een ge\u00efntegreerde supercondensator die bestand is tegen extreme temperaturen is de MiVue C545 Pro even sterk als betrouwbaar.<\/p>\n<p>De MiVue C545 Pro biedt ook 24\/7 bewaking met de optionele parkeer-functie (Smartbox voeding is vereist, wordt niet meegeleverd), zodat je ook gerust kunt zijn als je niet achter het stuur zit.<br \/>\nEn met een garantie van drie jaar kun je erop vertrouwen dat je investering voor de lange termijn beschermd is.<\/p>\n<p>De MiVue C545 Pro, gewoonweg superieure opnamen, dag en nacht.<\/p>\n<h2><b>Specificaties<\/b><\/h2>\n<ul>\n<li>Sony STARVIS CMOS-sensor<\/li>\n<li>Opnameresolutie: Full HD 1920&#215;1080 bij 60\/30 fps<\/li>\n<li>Kijkhoek: 140 graden<\/li>\n<li>Diafragma: F1.8<\/li>\n<li>Video bestandsindeling: .mp4 (H.264)<\/li>\n<li>HDR<\/li>\n<li>Schermgrootte: 2 inch<\/li>\n<li>micro SD-kaart: tot 256 GB<\/li>\n<li>Afmetingen in mm: 61 x 54,6 x 41,7<\/li>\n<li>Gewicht: 68 g<\/li>\n<li>Inclusief autolader (USB-C), 3M mount en statische ruitsticker<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<h1>Mio MiVue C545PRO dashcam Full HD+HDR+2M sensor<\/h1>\n","protected":false},"featured_media":3453,"template":"","meta":{"jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"product_brand":[],"product_cat":[24],"product_tag":[],"class_list":["post-3452","product","type-product","status-publish","has-post-thumbnail","product_cat-mivuec","product_shipping_class-gratisverzenden","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/product\/3452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/media\/3453"}],"wp:attachment":[{"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/media?parent=3452"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/product_brand?post=3452"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/product_cat?post=3452"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/miha.nl\/mio\/wp-json\/wp\/v2\/product_tag?post=3452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}